{"id":163,"date":"2017-02-14T19:39:50","date_gmt":"2017-02-14T19:39:50","guid":{"rendered":"https:\/\/www.simpletense.com\/blog\/?p=163"},"modified":"2022-06-20T16:13:38","modified_gmt":"2022-06-20T23:13:38","slug":"%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99","status":"publish","type":"post","link":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/","title":{"rendered":"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec"},"content":{"rendered":"<p>\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3offer\u7edd\u975e\u6613\u4e8b\u3002\u7559\u5b66\u751f\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.simpletense.com\/resume-service\/\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199<\/a><\/span>\uff0c$199\u641e\u5b9aResume+Cover Letter\uff01<br \/>\n<!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_58 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >\u6587\u7ae0\u76ee\u5f55 <\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E5%9F%BA%E6%9C%AC%E5%8E%9F%E5%88%99\" title=\"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u57fa\u672c\u539f\u5219\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u57fa\u672c\u539f\u5219<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E7%AE%80%E5%8E%86%E5%8C%85%E5%90%AB%E5%86%85%E5%AE%B9\" title=\"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u7b80\u5386\u5305\u542b\u5185\u5bb9\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u7b80\u5386\u5305\u542b\u5185\u5bb9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E6%8A%95%E9%80%92%E6%B3%A8%E6%84%8F%E4%BA%8B%E9%A1%B9\" title=\"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u6295\u9012\u6ce8\u610f\u4e8b\u9879\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u6295\u9012\u6ce8\u610f\u4e8b\u9879<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E4%B8%8B%E5%8D%95%E6%B5%81%E7%A8%8B\" title=\"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u4e0b\u5355\u6d41\u7a0b\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u4e0b\u5355\u6d41\u7a0b<\/a><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E5%9F%BA%E6%9C%AC%E5%8E%9F%E5%88%99\"><\/span><strong><span style=\"color: #000000;\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u57fa\u672c\u539f\u5219<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">1\uff09\u4e0d\u62d8\u6ce5\u4e8e\u5f62\u5f0f\uff0c\u5c55\u73b0\u4e2a\u4eba\u7279\u8272<\/span><br \/>\n2\uff09\u7ecf\u5386\u5185\u5bb9\u6309\u6761\u5217\u6765\u5199\uff0c\u6293\u53d6\u5173\u952e\u8bcd<br \/>\n3\uff09\u7b80\u5386\u5c3d\u91cf\u7528\u4e00\u9875\u7eb8<br \/>\n4\uff09\u5185\u5bb9\u5fc5\u987b\u771f\u5b9e\uff0c\u5207\u52ff\u5938\u5927<\/p>\n<p><span style=\"font-weight: 400;\">Resume<\/span><span style=\"font-weight: 400;\">\u4e00\u822c\u6ca1\u6709\u7279\u522b\u56fa\u5b9a\u7684\u5f62\u5f0f\uff0c\u5317\u7f8e\u6c42\u804c\u8005\u53ef\u4ee5\u6839\u636e\u4e2a\u4eba\u7684\u9700\u6c42\u6765\u9009\u62e9\u4e0d\u540c\u7684\u4fa7\u91cd\u70b9\u3002<\/span><\/p>\n<p>Skills Resume<br \/>\n\u8fd9\u79cd\u5f62\u5f0f\u7684Resume\u4ee5\u4e2a\u4eba\u5b66\u5386\u4e3a\u4e3b\u3002\u9002\u7528\u4e8e\u5e94\u5c4a\u6bd5\u4e1a\u751f\uff0c\u7531\u4e8e\u76f8\u5173\u5de5\u4f5c\u7ecf\u5386\u8f83\u5c11\uff0c\u6240\u4ee5\u628a\u91cd\u70b9\u653e\u5728\u5b66\u4e1a\u4e0a\u3002\u7a81\u51fa\u4e13\u4e1a\u77e5\u8bc6\u548c\u4e13\u4e1a\u80fd\u529b\u3002<\/p>\n<p>Chronological Resume<br \/>\n\u8fd9\u79cdResume\u4fa7\u91cd\u70b9\u5728\u5de5\u4f5c\u7ecf\u5386\u4e0a\uff0c\u5bf9\u4e8e\u5de5\u4f5c\u7ecf\u5386\u4e2d\u7684\u5185\u5bb9\u3001\u7ed3\u679c\u3001\u6210\u5c31\u7b49\u63cf\u8ff0\u5f97\u8f83\u4e3a\u8be6\u5c3d\u3002\u5e76\u4e14\u901a\u5e38\u662f\u4e0e\u76ee\u6807\u5c97\u4f4d\u76f8\u5173\u7684\u7ecf\u5386\uff0c\u6309\u65f6\u95f4\u7531\u8fd1\u81f3\u8fdc\u7684\u987a\u5e8f\u5217\u51fa\uff0c\u628a\u5de5\u4f5c\u7ecf\u5386\u653e\u5728\u5b66\u5386\u4e4b\u524d\u3002<\/p>\n<p>Functional Resume<br \/>\n\u4e0e\u7b2c\u4e8c\u79cd\u5f62\u5f0f\u76f8\u6bd4\uff0cFunctional Resume\u66f4\u52a0\u4fa7\u91cd\u804c\u80fd\u3002\u8fd9\u79cd\u5f62\u5f0f\u7684\u7b80\u5386\u6309\u7167\u4e0d\u540c\u7684\u5de5\u4f5c\u5f62\u5f0f\u6765\u5212\u5206\u5de5\u4f5c\u7ecf\u5386\uff0c\u65f6\u95f4\u4e0a\u4e0d\u4e00\u5b9a\u8fde\u8d2f\uff0c\u800c\u662f\u5c06\u4e0d\u540c\u5de5\u4f5c\u9636\u6bb5\u4e2d\u76f8\u540c\u804c\u52a1\u548c\u4e1a\u52a1\u5f52\u7eb3\u5728\u4e00\u8d77\u3002<\/p>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E7%AE%80%E5%8E%86%E5%8C%85%E5%90%AB%E5%86%85%E5%AE%B9\"><\/span><strong><span style=\"color: #000000;\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-<\/span><\/strong><strong><span style=\"color: #000000;\">\u7b80\u5386\u5305\u542b\u5185\u5bb9<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9419\" src=\"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-300x200.jpg\" alt=\"Resume\u7b80\u5386\u4ee3\u5199\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-300x200.jpg 300w, https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-1024x683.jpg 1024w, https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-768x512.jpg 768w, https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-1536x1024.jpg 1536w, https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/Resume\u7b80\u5386\u4ee3\u5199-2048x1365.jpg 2048w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><strong>\u57fa\u672c\u4fe1\u606f Personal Information<\/strong><br \/>\n<span style=\"font-weight: 400;\">\u7b80\u5386\u7684\u5f00\u5934\u8981\u5199\u6e05\u695a\u59d3\u540d\uff0c\u5730\u5740\uff0c\u8054\u7cfb\u65b9\u5f0f\u3002\u57fa\u672c\u4fe1\u606f\u4e00\u822c\u5199\u5728\u7b80\u5386\u7684\u6700\u4e0a\u65b9\uff0c\u4e2d\u95f4\u5904\u3002\u59d3\u540d\u7684\u5b57\u53f7\u8981\u66f4\u5927\u4e00\u4e9b\uff0c\u4f46\u662f\u4e0d\u53ef\u4ee5\u91c7\u7528\u82b1\u54e8\u7684\u5b57\u4f53\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u540d\u5b57\u7684\u5199\u6cd5\u4e5f\u6709\u8bb2\u7a76\u3002\u6709\u82f1\u6587\u540d\u5199\u6cd5\uff1aRose\uff08English name\uff09Zhang\uff08\u59d3\u6c0f\u62fc\u97f3\uff09\uff1b\u65e0\u82f1\u6587\u540d\u5199\u6cd5\uff1aMeijie \uff08\u540d\u5b57\u62fc\u97f3\uff09Fan\uff08 \u59d3\u6c0f\u62fc\u97f3\uff09\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u540d\u5b57\u4e0b\u65b9\u4e3a\u8054\u7cfb\u65b9\u5f0f\uff0c\u7535\u8bdd\u6b63\u786e\u5199\u6cd5\uff1axxx-xxx-xxxx \u3002\u82f1\u6587\u7b80\u5386\u4e2d\u4e0d\u9700\u8981\u5305\u542b\u4f60\u7684\u8eab\u9ad8\/\u5e74\u9f84\/\u751f\u65e5\/\u653f\u6cbb\u9762\u8c8c\uff0c\u4e5f\u4e0d\u9700\u8981\u5305\u542b\u4f60\u7684\u7167\u7247\u3002<\/span><\/p>\n<p><strong>\u6c42\u804c\u610f\u5411 Objective<\/strong><br \/>\n<span style=\"font-weight: 400;\">\u7edd\u5927\u591a\u6570\u60c5\u51b5\u4e0b\uff0c\u5199\u660e\u6c42\u804c\u610f\u5411\u80fd\u591f\u8ba9\u62db\u8058\u516c\u53f8\u66f4\u5feb\u4e86\u89e3\u6c42\u804c\u8005\u7684\u76ee\u6807\u804c\u4f4d\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u4f8b\u5982\uff1a Objective: Help ABC Aerospace achieve its mission of designing tomorrow&#8217;s technology today by joining the Navigation Software Development Team as a programmer.<\/span><\/p>\n<p><strong>\u6559\u80b2\u80cc\u666f Education<\/strong><br \/>\n<span style=\"font-weight: 400;\">\u6559\u80b2\u80cc\u666f\u4ece\u5927\u5b66\u5f00\u59cb\u5199\u8d77\uff0c\u5982\u679c\u4f60\u5927\u5b66\u5728\u8bfb\u6216\u8005\u5df2\u7ecf\u6bd5\u4e1a\uff0c\u4e0d\u9700\u8981\u5728\u7b80\u5386\u4e2d\u5305\u542b\u4efb\u4f55\u5927\u5b66\u524d\u7684\u4fe1\u606f\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u5b66\u6821\uff0c\u5b66\u6821\u6240\u5728\u7684\u57ce\u5e02\uff0c\u4e13\u4e1a\uff0c\u6240\u83b7\u5f97\u7684\u5b66\u4f4d\uff0c\u6bd5\u4e1a\u65f6\u95f4\u7b49\u4fe1\u606f\u662f\u5fc5\u987b\u7684\u3002\u4f60\u7684GPA\u4e0d\u662f\u5fc5\u987b\u7684\u3002\u5b9e\u9645\u4e0a\uff0c\u5982\u679c\u4f60\u7684GPA\u4f4e\u4e8e3.0\u7684\u8bdd\uff0c\u6700\u597d\u628aGPA\u7701\u7565\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u5982\u679c\u8fd8\u6709\u8f83\u91cd\u5927\u6216\u8005\u7279\u6b8a\u7684\u8363\u8a89\u6216\u8005\u5956\u9879\uff0c\u4e5f\u53ef\u4ee5\u9002\u5f53\u5217\u51fa\u3002<\/span><\/p>\n<p><strong>\u5de5\u4f5c\u7ecf\u5386 Experience<\/strong><br \/>\n<span style=\"font-weight: 400;\">\u5de5\u4f5c\u7ecf\u5386\u8fd9\u4e00\u90e8\u5206\u662f\u6839\u636e\u6c42\u804c\u8005\u4e2a\u4eba\u60c5\u51b5\u800c\u5b9a\u7684\u3002\u4f46\u662f\u5982\u679c\u5de5\u4f5c\u7ecf\u9a8c\u6bd4\u8f83\u4e30\u5bcc\uff0c\u53ea\u9700\u8981\u5217\u4e3e\u4e0e\u6c42\u804c\u76ee\u6807\u76f8\u5173\u7684\u5373\u53ef\uff0c\u4e0d\u5fc5\u5b8c\u5168\u5217\u4e3e\u51fa\u6240\u6709\u4ee5\u5f80\u5de5\u4f5c\u7ecf\u9a8c\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u6bcf\u4e00\u9879\u5de5\u4f5c\u7ecf\u5386\u9700\u8981\u5305\u62ec:\u516c\u53f8\u7684\u540d\u79f0\u548c\u6240\u5728\u57ce\u5e02\uff0c\u5c31\u804c\u7684\u65f6\u95f4\uff0c\u804c\u4f4d\u540d\u79f0\u548c\u4f60\u7684\u804c\u80fd\u3002\u6bcf\u4e00\u9879\u5de5\u4f5c\u7ecf\u5386\u7528\u4e09\u5230\u4e94\u4e2a\u77ed\u53e5\u63cf\u8ff0\uff0c\u5e76\u4e14\u7528Bullet Points\u6392\u5217\u3002\u63cf\u8ff0\u8fc7\u53bb\u7ecf\u5386\u7528\u8fc7\u53bb\u5f0f\uff0c\u73b0\u5728\u8fd8\u5728\u505a\u7684\uff0c\u7528\u4e00\u822c\u73b0\u5728\u65f6\u3002\u6240\u6709\u5de5\u4f5c\u7ecf\u9a8c\u7684\u5185\u5bb9\u8be6\u8ff0\u90fd\u5e94\u4ee5\u52a8\u8bcd\u5f00\u5934\uff0c\u5c31\u662f\u6240\u8c13\u7684action verbs\uff0c\u8f85\u52a9\u52a8\u8bcd\uff08make, do\u4e4b\u7c7b\uff09\u5c3d\u91cf\u5c11\u7528\u3002\u5217\u51fa\u5177\u4f53\u7684\u6570\u5b57\u6765\u91cf\u5316\u7ed3\u679c\uff0c\u4f8b\u5982\uff0c\u8282\u7701\u7684\u5f00\u652f\u6570\u91cf\uff0c\u670d\u52a1\u8fc7\u7684\u5ba2\u6237\u6570\u91cf\uff0c\u4ea7\u80fd\u589e\u52a0\u7684\u767e\u5206\u6bd4\u3002<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u5728\u8fd9\u91cc\u4ecb\u7ecd\u4e00\u79cd\u7ecf\u5178\u7684\u5de5\u4f5c\u7ecf\u5386\u5199\u4f5c\u65b9\u6cd5\u2014\u2014<span style=\"color: #000000;\">PAR\u9648\u8ff0\u6cd5<\/span><\/span><br \/>\n<span style=\"font-weight: 400;\">PAR\u5373Project, Activity, Results\u7684\u7f29\u5199\uff0c\u7b80\u5355\u6765\u8bf4\uff0c\u5c31\u662f\u4f7f\u7528Action Verbs\uff0c\u5e76\u4e14\u91c7\u7528\u4ee5\u4e0b\u683c\u5f0f\u6765\u63cf\u8ff0\u4f60\u7684\u5de5\u4f5c\u7ecf\u5386\uff1a<\/span><br \/>\n<span style=\"font-weight: 400;\">P\uff1aProject\u7684\u540d\u79f0\u3001\u80cc\u666f\u3001\u4efb\u52a1\u548c\u76ee\u6807<\/span><br \/>\n<span style=\"font-weight: 400;\">A\uff1a\u4f60\u5728\u8fd9\u4e2aProject\u4e2d\u626e\u6f14\u7684\u89d2\u8272\uff0c\u6240\u505a\u7684\u5de5\u4f5c\uff08Activity\uff09<\/span><br \/>\n<span style=\"font-weight: 400;\">R\uff1a\u4f60\u5728\u8fd9\u6bb5\u7ecf\u5386\u4e2d\u83b7\u5f97\u7684\u7ed3\u679c\uff08Results\uff09\uff0c \u6210\u679c\u548c\u6536\u76ca\u3002<\/span><\/p>\n<p><strong>\u5176\u4ed6\u4fe1\u606f Personal Profile or Hobbies<\/strong><br \/>\n<span style=\"font-weight: 400;\">\u8fd9\u90e8\u5206\u53ef\u4ee5\u5199\u7684\u5185\u5bb9\u5305\u62ec\u8bed\u8a00\u6280\u80fd\uff0c\u8ba1\u7b97\u673a\u6280\u80fd\uff0c\u63a5\u53d7\u8fc7\u7684\u8bad\u7ec3\uff0c\u4e2a\u4eba\u8bc4\u4ef7\u548c\u5174\u8da3\u7231\u597d\u7b49\u7b49\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">\u9700\u8981\u63d0\u9192\u5927\u5bb6\u7684\u662f\uff0c\u5174\u8da3\u7231\u597d\u7684\u90e8\u5206\uff0c\u91cd\u70b9\u7a81\u51fa\u4e0e\u8fd9\u4efd\u5de5\u4f5c\u6240\u9700\u6280\u80fd\u76f8\u5173\u7684\u5174\u8da3\u7231\u597d\u3002<\/span><\/p>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E6%8A%95%E9%80%92%E6%B3%A8%E6%84%8F%E4%BA%8B%E9%A1%B9\"><\/span><strong><span style=\"color: #000000;\">\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199<\/span><\/strong><strong><span style=\"color: #000000;\">-\u6295\u9012\u6ce8\u610f\u4e8b\u9879<\/span><\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">1\uff09\u8bf7\u7533\u8bf7\u4e00\u4e2a<\/span><span style=\"font-weight: 400;\">gmail <\/span><span style=\"font-weight: 400;\">\u4e4b\u7c7b\u7684\u6b63\u89c4\u90ae\u7bb1\uff0c\u628a\u59d3\u540d\u8bbe\u7f6e\u6210\u771f\u5b9e\u59d3\u540d\u3002\u6211\u4eec\u662f\u5728\u627e\u5de5\u4f5c\uff0c\u4e0d\u662f<\/span><span style=\"font-weight: 400;\">QQ<\/span><span style=\"font-weight: 400;\">\u70ab\u821e\u5bb6\u65cf\u62db\u4eb2\uff0c\u6240\u4ee5\u5343\u4e07\u522b\u7528<\/span><span style=\"font-weight: 400;\">QQ<\/span><span style=\"font-weight: 400;\">\u90ae\u7bb1\uff0c\u9876\u7740\u975e\u4e3b\u6d41\u7684\u6635\u79f0\u6295\u9012\u4f60\u7684\u7b80\u5386\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">2\uff09\u5efa\u8bae\u4f7f\u7528<\/span><span style=\"font-weight: 400;\">PDF<\/span><span style=\"font-weight: 400;\">\u683c\u5f0f\u6295\u9012\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">3\uff09\u6240\u6709\u6807\u70b9\u8bf7\u7528\u82f1\u6587\u7684\u534a\u89d2\u683c\u5f0f\u3002\u9017\u53f7\u540e\u9762\u8bb0\u5f97\u7a7a\u683c\u3002\u7b80\u5386\u91cc\u4e00\u822c\u7528\u4e0d\u5230\u53e5\u53f7\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">4\uff09\u8fd8\u5728\u4e0a\u5b66\u6216\u521a\u5de5\u4f5c\u51e0\u5e74\u7684\uff0c\u7b80\u5386\u6700\u597d\u53ea\u6709\u4e00\u9875\u3002\u4f46\u662f\u5de5\u7a0b\u7c7b\u7684\u5de5\u4f5c\u5141\u8bb8\u7b80\u5386\u957f\u8fbe\u4e24\u9875\uff0c\u6765\u8be6\u7ec6\u4ecb\u7ecd\u6bcf\u4e00\u4e2a\u4f60\u7684\u6280\u80fd\u548c\u6bcf\u4e00\u4e2aproject\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">5\uff09\u4e3a\u4e86\u907f\u514d\u6b67\u4e49\uff0c\u65e5\u671f\u5efa\u8bae\u5199\u6210<\/span><span style=\"font-weight: 400;\"> January 5, 2016 <\/span><span style=\"font-weight: 400;\">\u6216\u8005<\/span><span style=\"font-weight: 400;\"> 5 January, 2016 <\/span><span style=\"font-weight: 400;\">\u8fd9\u79cd\u683c\u5f0f\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">6\uff09\u59d3\u540d\u8981\u7edf\u4e00\u3002\u5982\u679c\u4f60\u7528\u82f1\u6587\u540d\uff0c\u90a3\u4e48\u5317\u7f8e\u6c42\u804c\u4e2d\u7684\u7533\u8bf7\u73af\u8282\uff0c\u90fd\u8bf7\u7528\u82f1\u6587\u540d\uff08\u63a8\u8350\u4fe1\u91cc\u3001\u90ae\u4ef6\u7b7e\u540d\u5904\u3001\u9762\u8bd5\u4e2d\uff09\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">7\uff09\u6587\u4ef6\u540d\u6700\u597d\u5b58\u4e3a<\/span><span style=\"font-weight: 400;\"> Zhang_CV.pdf <\/span><span style=\"font-weight: 400;\">\u6216\u8005<\/span><span style=\"font-weight: 400;\"> Zhang_Resume.docx <\/span><span style=\"font-weight: 400;\">\u8fd9\u6837\uff0c\u4ee5\u59d3\u6c0f\u5f00\u5934\u3001\u65e0\u7a7a\u683c\u3002<\/span><br \/>\n<span style=\"font-weight: 400;\">8\uff09\u7528\u5904\u5973\u5ea7\u7684\u5fc3\u6001\u53bb\u770b\u5f85\u6392\u7248\u3002<\/span>\u770b\u4f60\u7684\u7b80\u5386\uff0c\u7b2c\u4e00\u773c\u770b\u5230\u7684\u4f1a\u662f\u4ec0\u4e48\u5462\uff1f\u4e0d\u662f\u5185\u5bb9\uff0c\u4e0d\u662f\u4f60\u7684<span style=\"font-weight: 400;\">GPA<\/span><span style=\"font-weight: 400;\">\uff0c\u800c\u662f\u6574\u4e2a\u7b80\u5386\u7684\u98ce\u683c\u548c\u6392\u7248\u3002\u5728\u5236\u4f5c\u7b80\u5386\u7684\u65f6\u5019\uff0c\u8bf7\u4e00\u5b9a\u7528\u5f3a\u8feb\u75c7\u7684\u8981\u6c42\u6765\u89c4\u8303\u81ea\u5df1\u3002<span style=\"font-weight: 400;\">\u540c\u4e00\u7ea7\u522b\u7684\u5185\u5bb9\u7528\u540c\u6837\u7684\u5b57\u4f53\u3001\u5b57\u53f7\uff1b<\/span><span style=\"font-weight: 400;\">\u6bb5\u843d\u4e4b\u95f4\u7684\u95f4\u8ddd\u4e00\u5b9a\u8981\u76f8\u540c\uff1b<\/span><span style=\"font-weight: 400;\">\u6587\u5b57\u4e0e\u4e0a\u4e0b\u5de6\u53f3\u8fb9\u6846\u7684\u95f4\u8ddd\u8c03\u6574\u4e00\u81f4\u3002<\/span><\/span><\/p>\n<p><a href=\"https:\/\/www.simpletense.com\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-856 aligncenter\" src=\"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/\u5317\u7f8e\u6c42\u804c\u8d44\u8baf-396x198.png\" alt=\"\u5317\u7f8e\u6c42\u804c\" width=\"396\" height=\"198\" srcset=\"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/\u5317\u7f8e\u6c42\u804c\u8d44\u8baf-396x198.png 396w, https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/\u5317\u7f8e\u6c42\u804c\u8d44\u8baf.png 700w\" sizes=\"(max-width: 396px) 100vw, 396px\" \/><\/a><br \/>\n<span style=\"font-weight: 400;\">\u5f88\u591a\u65f6\u5019\uff0c\u5176\u5b9e\u540c\u9f84\u4eba\u7684\u7ecf\u5386\u4e0d\u89c1\u5f97\u6bd4\u4f60\u4e30\u5bcc\u591a\u5c11\uff0c\u7b80\u5386\u4e5f\u4e0d\u89c1\u5f97\u771f\u7684\u6bd4\u4f60\u725b\u903c\u591a\u5c11\u3002<\/span> <span style=\"font-weight: 400;\">\u4f46\u662f\u7b80\u5386\u901a\u8fc7\u7b5b\u9009\u7684\u4eba\u90fd\u6709\u4e00\u4e2a\u540c\u6837\u7684\u4f18\u70b9\uff0c\u5c31\u662f\u4ed6\u4eec\u5728\u7b80\u5386\u4e0a\u82b1\u8d39\u7684\u5fc3\u601d\uff0c\u6bd4\u540c\u9f84\u4eba\u591a\u5f97\u591a\u3002<\/span><\/p>\n<p>SimpleTense<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/www.simpletense.com\/resume-service\/\">\u82f1\u6587\u7b80\u5386\u4ee3\u5199<\/a><\/span>\u670d\u52a1\uff0c\u8d44\u6df1HR\u4e3a\u4f60\u6253\u9020\u4e13\u4e1a\u82f1\u6587\u7b80\u5386\uff0c\u5e2e\u52a9\u4f60\u8fc8\u51fa\u5317\u7f8e\u6c42\u804c\u6210\u529f\u7b2c\u4e00\u6b65\uff01<br \/>\n1\uff09\u597d\u7b80\u5386\u662f\u6c42\u804c\u6210\u529f\u7b2c\u4e00\u6b65\uff0c\u5b9a\u5236\u82f1\u6587\u7b80\u5386\u63d0\u9ad850%\u5c31\u4e1a\u6210\u529f\u7387<br \/>\n2\uff09\u5b66\u6821Career Center\u592a\u96be\u7ea6\uff1f\u8d44\u6df1\u6c42\u804c\u5bfc\u5e08\u5168\u5929\u5019\u670d\u52a1\uff0c\u6700\u5feb72\u5c0f\u65f6\u4e4b\u5185\u4ea4\u4ed8<br \/>\n3\uff09\u5b8c\u7f8e\u7684\u6392\u7248\u8bbe\u8ba1\u548c\u5173\u952e\u8bcd\u4f18\u5316\uff0c\u8ba9\u4f60\u6beb\u4e0d\u8d39\u529b\u5728\u4eba\u7fa4\u4e2d\u8131\u9896\u800c\u51fa<br \/>\n4\uff09100%\u6ee1\u610f\u4fdd\u8bc1\uff0c\u62d2\u7edd\u5957\u7528\u6a21\u677f\uff0c14\u5929\u5185\u514d\u8d39\u4fee\u6539<\/p>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"%E5%8C%97%E7%BE%8EResume%E7%AE%80%E5%8E%86%E4%BB%A3%E5%86%99-%E4%B8%8B%E5%8D%95%E6%B5%81%E7%A8%8B\"><\/span><strong>\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199-\u4e0b\u5355\u6d41\u7a0b<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Step 1: \u5feb\u901f\u4e0b\u5355\uff0c\u4e0a\u4f20\u6750\u6599<br \/>\n\u4e09\u5206\u949f\u5373\u53ef\u5b8c\u6210\u4e0b\u5355\uff0c\u4e0b\u5355\u65f6\u53ef\u4e0a\u4f20\u4e2a\u4eba\u76f8\u5173\u8d44\u6599<\/p>\n<p>Step 2: \u586b\u5199\u95ee\u5377\uff0c\u5b89\u6392\u5bfc\u5e08<br \/>\n\u5b8c\u6210\u4e00\u4efd\u8c03\u67e5\u95ee\u5377\uff0c\u5e2e\u52a9\u5bfc\u5e08\u66f4\u597d\u5730\u4e86\u89e3\u4f60\u7684\u80cc\u666f\uff0c\u76f8\u5173\u4e13\u4e1a\u5bfc\u5e08\u4e3a\u4f60\u4e2a\u6027\u5316\u5b9a\u5236Resume<\/p>\n<p>Step 3: \u5bfc\u5e08\u5199\u4f5c\uff0c\u91cf\u8eab\u5b9a\u5236<br \/>\n\u91cd\u70b9\u7a81\u51fa\u4e2a\u4eba\u6210\u5c31\u548c\u5de5\u4f5c\u7ecf\u9a8c, \u6253\u9020\u6700\u5177\u7ade\u4e89\u529b\u7684\u82f1\u6587\u7b80\u5386<\/p>\n<p>Step 4: \u5b8c\u7a3f\u4f20\u9001\uff0c\u6ee1\u610f\u4fdd\u8bc1<br \/>\n\u8ba2\u5355\u5b8c\u6210\u540e\uff0c\u6211\u4eec\u4f1a\u5c06\u7b80\u5386\u53d1\u9001\u81f3\u4f60\u7684\u90ae\u7bb1\uff0c\u6700\u5feb72\u5c0f\u65f6\u4ea4\u4ed8\uff0c14\u5929\u5185\u514d\u8d39\u4fee\u6539<\/p>\n<p style=\"text-align: center;\"><a class=\"maxbutton-1 maxbutton\" href=\"https:\/\/www.simpletense.com\/essay-service\"><span class='mb-text'>\u73b0\u5728\u6ce8\u518c \u5373\u9001$20<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3offer\u7edd\u975e\u6613\u4e8b\u3002\u7559\u5b66\u751f\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199\uff0c$199\u641e\u5b9aResume+Cover Letter\uff01<\/p>\n","protected":false},"author":1,"featured_media":855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46],"tags":[1894,49,47,1895,1896],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u5317\u7f8eResume\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec<\/title>\n<meta name=\"description\" content=\"\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3\u7684\u5b9e\u4e60\u6216\u5de5\u4f5c\u7edd\u975e\u6613\u4e8b\u3002\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u6211\u4eec\u90fd\u8bf4\u7b80\u5386\u662f\u4e00\u5757\u6572\u95e8\u7816\u3002\u540c\u6837\u662f\u6572\u95e8\u7816\uff0c\u6709\u7684\u4eba\u6572\u5f00\u4e86\u95e8\uff0c\u6709\u7684\u4eba\u5374\u6572\u788e\u4e86\u7816\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.simpletense.com\/blog\/\u5317\u7f8e\u6c42\u804cresume\u4ee3\u5199\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5317\u7f8eResume\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec\" \/>\n<meta property=\"og:description\" content=\"\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3\u7684\u5b9e\u4e60\u6216\u5de5\u4f5c\u7edd\u975e\u6613\u4e8b\u3002\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u6211\u4eec\u90fd\u8bf4\u7b80\u5386\u662f\u4e00\u5757\u6572\u95e8\u7816\u3002\u540c\u6837\u662f\u6572\u95e8\u7816\uff0c\u6709\u7684\u4eba\u6572\u5f00\u4e86\u95e8\uff0c\u6709\u7684\u4eba\u5374\u6572\u788e\u4e86\u7816\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.simpletense.com\/blog\/\u5317\u7f8e\u6c42\u804cresume\u4ee3\u5199\/\" \/>\n<meta property=\"og:site_name\" content=\"\u6388\u4eba\u4ee5\u9c7c\u4e0d\u5982\u6388\u4eba\u4ee5\u6e14\uff0c\u5404\u79d1\u5199\u4f5c\u6a21\u677f\u968f\u65f6\u4e0b\u8f7d\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/simpletenseedu\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-14T19:39:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-20T23:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/\u5317\u7f8e\u6c42\u804c-Resume.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Simpletense\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simpletense\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5317\u7f8eResume\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec","description":"\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3\u7684\u5b9e\u4e60\u6216\u5de5\u4f5c\u7edd\u975e\u6613\u4e8b\u3002\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u6211\u4eec\u90fd\u8bf4\u7b80\u5386\u662f\u4e00\u5757\u6572\u95e8\u7816\u3002\u540c\u6837\u662f\u6572\u95e8\u7816\uff0c\u6709\u7684\u4eba\u6572\u5f00\u4e86\u95e8\uff0c\u6709\u7684\u4eba\u5374\u6572\u788e\u4e86\u7816\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.simpletense.com\/blog\/\u5317\u7f8e\u6c42\u804cresume\u4ee3\u5199\/","og_locale":"en_US","og_type":"article","og_title":"\u5317\u7f8eResume\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec","og_description":"\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3\u7684\u5b9e\u4e60\u6216\u5de5\u4f5c\u7edd\u975e\u6613\u4e8b\u3002\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u6211\u4eec\u90fd\u8bf4\u7b80\u5386\u662f\u4e00\u5757\u6572\u95e8\u7816\u3002\u540c\u6837\u662f\u6572\u95e8\u7816\uff0c\u6709\u7684\u4eba\u6572\u5f00\u4e86\u95e8\uff0c\u6709\u7684\u4eba\u5374\u6572\u788e\u4e86\u7816\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002","og_url":"https:\/\/www.simpletense.com\/blog\/\u5317\u7f8e\u6c42\u804cresume\u4ee3\u5199\/","og_site_name":"\u6388\u4eba\u4ee5\u9c7c\u4e0d\u5982\u6388\u4eba\u4ee5\u6e14\uff0c\u5404\u79d1\u5199\u4f5c\u6a21\u677f\u968f\u65f6\u4e0b\u8f7d","article_publisher":"https:\/\/www.facebook.com\/simpletenseedu","article_published_time":"2017-02-14T19:39:50+00:00","article_modified_time":"2022-06-20T23:13:38+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/\u5317\u7f8e\u6c42\u804c-Resume.png","type":"image\/png"}],"author":"Simpletense","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Simpletense","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#article","isPartOf":{"@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/"},"author":{"name":"Simpletense","@id":"https:\/\/www.simpletense.com\/blog\/#\/schema\/person\/8f49608d71bb5bb282863500e18ff346"},"headline":"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec","datePublished":"2017-02-14T19:39:50+00:00","dateModified":"2022-06-20T23:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/www.simpletense.com\/blog\/#organization"},"keywords":["\u5317\u7f8eresume\u4ee3\u5199","\u5317\u7f8e\u627e\u5de5\u4f5c","\u5317\u7f8e\u6c42\u804c","\u5317\u7f8e\u7b80\u5386\u4ee3\u5199","\u82f1\u6587\u7b80\u5386\u4ee3\u5199"],"articleSection":["\u6c42\u804c\u54a8\u8be2"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/","url":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/","name":"\u5317\u7f8eResume\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec","isPartOf":{"@id":"https:\/\/www.simpletense.com\/blog\/#website"},"datePublished":"2017-02-14T19:39:50+00:00","dateModified":"2022-06-20T23:13:38+00:00","description":"\u5317\u7f8e\u6c42\u804c\u8def\u6f2b\u6f2b\uff0c\u4ece\u6b63\u5f0f\u5f00\u59cb\u6295\u9012\u7b80\u5386\u5230\u6700\u7ec8\u62ff\u5230\u7406\u60f3\u7684\u5b9e\u4e60\u6216\u5de5\u4f5c\u7edd\u975e\u6613\u4e8b\u3002\u6c42\u804c\u9053\u8def\u4e0a\u901a\u5e38\u4f1a\u9047\u5230\u5404\u79cd\u56f0\u60d1\u548c\u632b\u6298\u3002\u6211\u4eec\u90fd\u8bf4\u7b80\u5386\u662f\u4e00\u5757\u6572\u95e8\u7816\u3002\u540c\u6837\u662f\u6572\u95e8\u7816\uff0c\u6709\u7684\u4eba\u6572\u5f00\u4e86\u95e8\uff0c\u6709\u7684\u4eba\u5374\u6572\u788e\u4e86\u7816\u3002\u8c28\u4ee5\u6b64\u6587\u732e\u7ed9\u6240\u6709\u88abResume\u903c\u75af\u7684\u540c\u5b66\u4eec\uff0c\u6559\u4f60\u5982\u4f55\u7528Resume\u6253\u5f00\u6c42\u804c\u7684\u5927\u95e8\u3002","breadcrumb":{"@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.simpletense.com\/blog\/%e5%8c%97%e7%be%8e%e6%b1%82%e8%81%8cresume%e4%bb%a3%e5%86%99\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.simpletense.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u5317\u7f8eResume\u7b80\u5386\u4ee3\u5199\uff1a\u5982\u4f55\u5199\u597dResume\uff1f\u732e\u7ed9\u6240\u6709\u88ab\u82f1\u6587\u7b80\u5386\u903c\u75af\u7684\u540c\u5b66\u4eec"}]},{"@type":"WebSite","@id":"https:\/\/www.simpletense.com\/blog\/#website","url":"https:\/\/www.simpletense.com\/blog\/","name":"\u6388\u4eba\u4ee5\u9c7c\u4e0d\u5982\u6388\u4eba\u4ee5\u6e14\uff0c\u5404\u79d1\u5199\u4f5c\u6a21\u677f\u968f\u65f6\u4e0b\u8f7d","description":"Essay\u4ee3\u5199 | \u8bba\u6587\u4ee3\u5199 | essay \u6a21\u677f | \u7f8e\u56fd\u8bba\u6587\u4ee3\u5199 | \u52a0\u62ff\u5927\u8bba\u6587\u4ee3\u5199","publisher":{"@id":"https:\/\/www.simpletense.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.simpletense.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.simpletense.com\/blog\/#organization","name":"SimpleTense","url":"https:\/\/www.simpletense.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.simpletense.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/logo.png","contentUrl":"https:\/\/www.simpletense.com\/blog\/wp-content\/uploads\/2017\/02\/logo.png","width":510,"height":86,"caption":"SimpleTense"},"image":{"@id":"https:\/\/www.simpletense.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/simpletenseedu","https:\/\/www.linkedin.com\/company\/simpletense-education"]},{"@type":"Person","@id":"https:\/\/www.simpletense.com\/blog\/#\/schema\/person\/8f49608d71bb5bb282863500e18ff346","name":"Simpletense","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.simpletense.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9ce2908ccd0230b210aa69a7162cab9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ce2908ccd0230b210aa69a7162cab9f?s=96&d=mm&r=g","caption":"Simpletense"},"description":"\u60a8\u82e6\u82e6\u6323\u624e\u4e0d\u5982\u5c06\u8bba\u6587\u4ea4\u7ed9\u6211\u4eec\uff0c\u8bba\u6587\u4ee3\u5199\u5e73\u5747\u5206\u9ad8\u8fbeA-\uff0c\u4e0d\u6ee1\u610f\u5168\u989d\u9000\u6b3e\uff0c100%\u51c6\u65f6\/\u63d0\u524d\u4ea4\u4ed8\uff0c100%\u65e0\u4f5c\u5f0aTurnitin\u514d\u8d39\u68c0\u6d4b\uff0c\u6700\u5feb12\u5c0f\u65f6\u4ea4\u4ed8","sameAs":["http:\/\/simpletense.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/posts\/163"}],"collection":[{"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":17,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"predecessor-version":[{"id":9420,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/posts\/163\/revisions\/9420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/media\/855"}],"wp:attachment":[{"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simpletense.com\/blog\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}